{"id":38,"count":7,"description":"","link":"https:\/\/nebu.la\/blog\/tag\/assets\/","name":"assets","slug":"assets","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>assets Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nebu.la\/blog\/tag\/assets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"assets Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nebu.la\/blog\/tag\/assets\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@join_nebula\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/nebu.la\/blog\/tag\/assets\/\",\"url\":\"https:\/\/nebu.la\/blog\/tag\/assets\/\",\"name\":\"assets Archives -\",\"isPartOf\":{\"@id\":\"https:\/\/nebu.la\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/nebu.la\/blog\/tag\/assets\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nebu.la\/blog\/tag\/assets\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nebu.la\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"assets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nebu.la\/blog\/#website\",\"url\":\"https:\/\/nebu.la\/blog\/\",\"name\":\"\",\"description\":\"Welcome to the Nebula Blog. Check out recent articles below.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nebu.la\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"assets Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nebu.la\/blog\/tag\/assets\/","og_locale":"en_US","og_type":"article","og_title":"assets Archives -","og_url":"https:\/\/nebu.la\/blog\/tag\/assets\/","twitter_card":"summary_large_image","twitter_site":"@join_nebula","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nebu.la\/blog\/tag\/assets\/","url":"https:\/\/nebu.la\/blog\/tag\/assets\/","name":"assets Archives -","isPartOf":{"@id":"https:\/\/nebu.la\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/nebu.la\/blog\/tag\/assets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/nebu.la\/blog\/tag\/assets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nebu.la\/blog\/"},{"@type":"ListItem","position":2,"name":"assets"}]},{"@type":"WebSite","@id":"https:\/\/nebu.la\/blog\/#website","url":"https:\/\/nebu.la\/blog\/","name":"","description":"Welcome to the Nebula Blog. Check out recent articles below.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nebu.la\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/nebu.la\/blog\/wp-json\/wp\/v2\/tags\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nebu.la\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/nebu.la\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/nebu.la\/blog\/wp-json\/wp\/v2\/posts?tags=38"},{"href":"https:\/\/nebu.la\/blog\/wp-json\/wp\/v2\/tribe_events?tags=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}